{"id":76,"date":"2025-03-03T14:12:00","date_gmt":"2025-03-03T13:12:00","guid":{"rendered":"http:\/\/localhost:8888\/wordpress\/?p=76"},"modified":"2025-07-16T15:10:50","modified_gmt":"2025-07-16T13:10:50","slug":"erfolgreiche-dan-pruefungen","status":"publish","type":"post","link":"https:\/\/karate-zentrum-pforzheim.de\/index.php\/2025\/03\/03\/erfolgreiche-dan-pruefungen\/","title":{"rendered":"Erfolgreiche Dan-Pr\u00fcfungen"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-3195\" src=\"http:\/\/localhost:8888\/wordpress\/wp-content\/uploads\/2016\/09\/Dan_pruefung01-e1752671212701-150x150.webp\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/karate-zentrum-pforzheim.de\/wp-content\/uploads\/2016\/09\/Dan_pruefung01-e1752671212701-150x150.webp 150w, https:\/\/karate-zentrum-pforzheim.de\/wp-content\/uploads\/2016\/09\/Dan_pruefung01-e1752671212701-90x90.webp 90w, https:\/\/karate-zentrum-pforzheim.de\/wp-content\/uploads\/2016\/09\/Dan_pruefung01-e1752671212701-100x100.webp 100w, https:\/\/karate-zentrum-pforzheim.de\/wp-content\/uploads\/2016\/09\/Dan_pruefung01-e1752671212701-370x370.webp 370w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-3196\" src=\"http:\/\/localhost:8888\/wordpress\/wp-content\/uploads\/2016\/09\/Dan_pruefung02-150x150.webp\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/karate-zentrum-pforzheim.de\/wp-content\/uploads\/2016\/09\/Dan_pruefung02-150x150.webp 150w, https:\/\/karate-zentrum-pforzheim.de\/wp-content\/uploads\/2016\/09\/Dan_pruefung02-90x90.webp 90w, https:\/\/karate-zentrum-pforzheim.de\/wp-content\/uploads\/2016\/09\/Dan_pruefung02-100x100.webp 100w, https:\/\/karate-zentrum-pforzheim.de\/wp-content\/uploads\/2016\/09\/Dan_pruefung02-370x370.webp 370w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/p>\n<p>Nach schwei\u00dftreibenden Vorbereitungen haben wir wieder drei Mitglieder unseres Dojos erfolgreiche Dan-Pr\u00fcfungen abgelegt. Die Pr\u00fcfung zum ersten Dan haben Rigon und Rinor bestanden.<\/p>\n<p>Felix Tang hat die Pr\u00fcfung zum zweiten Dan gemeistert.<\/p>\n<p>Herzlichen Gl\u00fcckwunsch !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach schwei\u00dftreibenden Vorbereitungen haben wir wieder drei Mitglieder unseres Dojos erfolgreiche Dan-Pr\u00fcfungen abgelegt. Die Pr\u00fcfung zum ersten Dan haben Rigon und Rinor bestanden. Felix Tang hat die Pr\u00fcfung zum zweiten Dan gemeistert. Herzlichen Gl\u00fcckwunsch !<\/p>\n","protected":false},"author":2,"featured_media":3195,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[82,83],"class_list":["post-76","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-dan-pruefungen","tag-felix-tang"],"_links":{"self":[{"href":"https:\/\/karate-zentrum-pforzheim.de\/index.php\/wp-json\/wp\/v2\/posts\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/karate-zentrum-pforzheim.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/karate-zentrum-pforzheim.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/karate-zentrum-pforzheim.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/karate-zentrum-pforzheim.de\/index.php\/wp-json\/wp\/v2\/comments?post=76"}],"version-history":[{"count":2,"href":"https:\/\/karate-zentrum-pforzheim.de\/index.php\/wp-json\/wp\/v2\/posts\/76\/revisions"}],"predecessor-version":[{"id":3199,"href":"https:\/\/karate-zentrum-pforzheim.de\/index.php\/wp-json\/wp\/v2\/posts\/76\/revisions\/3199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/karate-zentrum-pforzheim.de\/index.php\/wp-json\/wp\/v2\/media\/3195"}],"wp:attachment":[{"href":"https:\/\/karate-zentrum-pforzheim.de\/index.php\/wp-json\/wp\/v2\/media?parent=76"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/karate-zentrum-pforzheim.de\/index.php\/wp-json\/wp\/v2\/categories?post=76"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/karate-zentrum-pforzheim.de\/index.php\/wp-json\/wp\/v2\/tags?post=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}